{"id":6811,"date":"2025-11-17T15:15:00","date_gmt":"2025-11-17T12:15:00","guid":{"rendered":"https:\/\/kek10.gr\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/"},"modified":"2026-02-06T14:44:02","modified_gmt":"2026-02-06T11:44:02","slug":"nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia","status":"publish","type":"post","link":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/","title":{"rendered":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA &#8211; NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6811\" class=\"elementor elementor-6811 elementor-6806\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01c23f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01c23f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5a79fea\" data-id=\"5a79fea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07a9a70 elementor-widget elementor-widget-text-editor\" data-id=\"07a9a70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>ORA FORMAZIONE 100% A DISTANZA &#8211; NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!<\/strong><\/h2><p>Lo scopo del programma \u00e8 l&#8217;aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.<\/p><p>Nello specifico, il programma mira all&#8217;acquisizione e\/o all&#8217;aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\u00e9 all&#8217;ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze del mercato del lavoro in settori dell&#8217;economia con prospettive di crescita.<\/p><p>I dipendenti che soddisfano le seguenti condizioni possono partecipare all&#8217;azione:<\/p><ul><li>Essere lavoratori dipendenti del settore privato con orario di lavoro fisso o a turni.<\/li><\/ul><ul><li>Avere completato almeno l&#8217;istruzione obbligatoria.<\/li><\/ul><p>Non hanno diritto a partecipare al programma <strong>coloro che hanno frequentato un ciclo precedente dello stesso programma sulle Competenze Digitali e Verdi (Azione 16913).<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec789f3 uael-faq-box-layout-yes align-at-left elementor-widget elementor-widget-uael-faq\" data-id=\"ec789f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id='uael-faq-wrapper-247' class=\"uael-faq-wrapper\">\n\t\t\t\t<div class=\"uael-faq-container uael-faq-layout-accordion\" data-layout=\"toggle\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-8627082\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h4 class=\"uael-question-8627082 uael-question-span\" tabindex=\"0\" id=\"uael-faq-1-6a97beaadc7d5\">BENEFICIARI - DIRITTO DI PARTECIPAZIONE<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p><strong>\u2714\ufe0f<\/strong><strong> Lavoratori <\/strong>Dipendenti del settore privato<\/p><p> <\/p><p>\u00c8 condizione necessaria che i lavoratori partecipanti abbiano un'et\u00e0 <strong>superiore ai 18 anni<\/strong> e abbiano completato <strong>almeno<\/strong> <strong>l'istruzione obbligatoria<\/strong> (scuola media inferiore).<\/p><p> <\/p><p>Il programma prevede la fornitura di <strong>formazione teorica della durata massima di 150 ore<\/strong>, che porta all'acquisizione di conoscenze e competenze con la relativa <strong>certificazione gratuita<\/strong> tramite enti indipendenti.<\/p><p> <\/p><p>L'obiettivo \u00e8 che i<strong> beneficiari <\/strong><strong>migliorino le loro prospettive professionali ed economiche<\/strong>, ottenendo una certificazione riconosciuta a livello internazionale, che andr\u00e0 a soddisfare le moderne esigenze delle aziende in termini di modernizzazione e competitivit\u00e0.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-02f55a5\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h4 class=\"uael-question-02f55a5 uael-question-span\" tabindex=\"0\" id=\"uael-faq-2-6a97beaadc7fd\">OGGETTO DELLA FORMAZIONE <\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><h3><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/kek10.gr\/wp-content\/uploads\/2025\/07\/%CE%A4%CE%B5%CF%87%CE%BD%CE%BF%CE%BB%CE%BF%CE%B3%CE%B9%CE%BA%CF%8C%CF%82-%CE%9C%CE%B5%CF%84%CE%B1%CF%83%CF%87%CE%B7%CE%BC%CE%B1%CF%84%CE%B9%CF%83%CE%BC%CF%8C%CF%82-%CE%BA%CE%B1%CE%B9-%CE%A8%CE%B7%CF%86%CE%B9%CE%B1%CE%BA%CE%AE-%CE%9C%CE%B5%CF%84%CE%AC%CE%B2%CE%B1%CF%83%CE%B7-%CF%83%CF%84%CE%BF%CE%BD-%CE%94%CE%B7%CE%BC%CF%8C%CF%83%CE%B9%CE%BF-%CE%BA%CE%B1%CE%B9-%CF%83%CF%84%CE%BF%CE%BD-%CE%99%CE%B4%CE%B9%CF%89%CF%84%CE%B9%CE%BA%CF%8C-%CE%A4%CE%BF%CE%BC%CE%AD%CE%B1.pdf\"><strong>Trasformazione Tecnologica e Transizione Digitale nelle Imprese<\/strong> (Settore Pubblico e Privato)<\/a><\/span><\/h3><p>Il KEK10, dopo l'annuncio del DYPA per la scelta obbligatoria di un ambito di formazione, ha progettato <strong>la Formazione di Eccellenza<\/strong> che viene a coprire l'<strong>Esigenza n. 1 del Mercato del Lavoro<\/strong>, che non \u00e8 altro che la <strong>Modernizzazione Digitale delle Imprese<\/strong>.<\/p><p> <\/p><p><strong>\u201cOrmai tutto \u00e8 digitale\u201d<\/strong> ha sottolineato il responsabile del Servizio Pubblico per l'Impiego, evidenziando l'urgente necessit\u00e0 del mercato (settore pubblico e privato) di dotarsi di personale qualificato.<\/p><p><strong> <\/strong><\/p><p><strong>Insieme passiamo dal \u201cvecchio\u201d all'\u201cintelligente\u201d, imparando nuove tecnologie e strumenti digitali, sfruttando le potenzialit\u00e0 dell'Intelligenza Artificiale.<\/strong><\/p><p> <\/p><p>La trasformazione tecnologica e la transizione digitale non sono il futuro \u2013 sono il presente. Sempre pi\u00f9 aziende e organizzazioni investono nella transizione digitale e cercano persone che conoscano i principi fondamentali e le applicazioni pratiche. <\/p><p> <\/p><p>Diventa <strong>pi\u00f9 competitivo<\/strong> nel mercato del lavoro!<\/p><p> <\/p><p><strong>Acquisisci qualifiche<\/strong> richieste da aziende ed enti pubblici!<\/p><p> <\/p><p><strong>La nuova era \u00e8 qui! Non restare indietro, inizia oggi! <\/strong><\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-13c7d51\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h4 class=\"uael-question-13c7d51 uael-question-span\" tabindex=\"0\" id=\"uael-faq-3-6a97beaadc813\">METODO DI IMPLEMENTAZIONE  <\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Formazione a distanza in modalit\u00e0 asincrona.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-6a70949\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h4 class=\"uael-question-6a70949 uael-question-span\" tabindex=\"0\" id=\"uael-faq-4-6a97beaadc826\">DIPARTIMENTI DI FORMAZIONE<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>L'inserimento nei corsi avviene gradualmente e in base alla disponibilit\u00e0 del beneficiario, con orari flessibili per agevolare al meglio i lavoratori.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-bfceea3\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h4 class=\"uael-question-bfceea3 uael-question-span\" tabindex=\"0\" id=\"uael-faq-5-6a97beaadc839\">INDENNIT\u00c0 DI ISTRUZIONE  <\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>L'indennit\u00e0 di formazione ammonta a <strong>750 euro<\/strong> (5 euro\/ora di formazione).<\/p><p> <\/p><h5><em>*L \u201cimporto definitivo dell\u201d indennit\u00e0 di formazione dovrebbe essere chiarito con la pubblicazione del bando.<\/em><\/h5><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e1a561 elementor-widget elementor-widget-spacer\" data-id=\"6e1a561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a4b2f0 elementor-widget elementor-widget-text-editor\" data-id=\"7a4b2f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"MsoNormal\"><b>Per informazioni sui termini e le condizioni di partecipazione, gli interessati possono consultare il sito ufficiale del programma <\/b><a href=\"http:\/\/www.voucher.gov.gr\/?fbclid=IwAR3GD9QYqr96nPkYDx_L1oCKS-cki26dJHt-zKlKevr8MPFBRrZ_i2K9VRE\" target=\"_blank\" rel=\"noopener\"><b>www.voucher.gov.gr<\/b><\/a><\/p><p class=\"MsoNormal\"><b><\/b><b>Per maggiori informazioni puoi compilare il modulo e sarai contattato.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f05fa84\" data-id=\"f05fa84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb1102d eael-wpforms-labels-yes eael-wpforms-form-button-custom elementor-widget elementor-widget-eael-wpforms\" data-id=\"bb1102d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"eael-contact-form eael-wpforms eael-wpforms-align-default\">\n                                <div class=\"wpforms-container \" id=\"wpforms-6832\"><form id=\"wpforms-form-6832\" class=\"wpforms-validate wpforms-form\" data-formid=\"6832\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/it\/wp-json\/wp\/v2\/posts\/6811\" data-token=\"8aaecffbf84963d2bdc46b7e915465aa\" data-token-time=\"1788332342\"><div class=\"wpforms-head-container\"><div class=\"wpforms-description\">SI PREGA DI COMPILARE IL MODULO DI INTERESSE SOTTOSTANTE CON CARATTERI MAIUSCOLI GRECI.<\/div><\/div><noscript class=\"wpforms-error-noscript\">Per favore, attiva JavaScript nel tuo browser per completare questo modulo.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-6832-field_14-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"14\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_14\">Cognome   <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6832-field_14\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][14]\" placeholder=\"Cognome*\" required><\/div><div id=\"wpforms-6832-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_0\">Nome <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6832-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Nome*\" required><\/div><div id=\"wpforms-6832-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_3\">Telefono di contatto <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6832-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"Telefono di contatto*\" required><\/div><div id=\"wpforms-6832-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_1\">E-mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6832-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"E-mail*\" spellcheck=\"false\" required><\/div><div id=\"wpforms-6832-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"9\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_9\">Citt\u00e0 di residenza <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6832-field_9\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][9]\" placeholder=\"Citt\u00e0 di residenza*\" required><\/div><div id=\"wpforms-6832-field_15-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"15\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_15\">TK<\/label><input type=\"text\" id=\"wpforms-6832-field_15\" class=\"wpforms-field-large\" name=\"wpforms[fields][15]\" placeholder=\"TK\" ><\/div><div id=\"wpforms-6832-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"16\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_16\">Anno di nascita <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6832-field_16\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][16]\" placeholder=\"Anno di nascita*\" required><\/div><div id=\"wpforms-6832-field_18-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-6832-field_18\">Livello di istruzione <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-6832-field_18\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][18]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Seleziona<\/option><option value=\"Terziario\"  class=\"choice-1 depth-1\"  >Terziario<\/option><option value=\"Secondario\"  class=\"choice-2 depth-1\"  >Secondario<\/option><option value=\"Primario\"  class=\"choice-3 depth-1\"  >Primario<\/option><\/select><\/div><div id=\"wpforms-6832-field_25-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-trigger wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-6832-field_25\">Stato di occupazione <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-6832-field_25\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][25]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Seleziona<\/option><option value=\"Disoccupato\"  class=\"choice-1 depth-1\"  >Disoccupato<\/option><option value=\"Dipendente\"  class=\"choice-2 depth-1\"  >Dipendente<\/option><\/select><\/div><div id=\"wpforms-6832-field_17-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-hide\" data-field-type=\"text\" data-field-id=\"17\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_17\">Area di lavoro<\/label><input type=\"text\" id=\"wpforms-6832-field_17\" class=\"wpforms-field-large\" name=\"wpforms[fields][17]\" placeholder=\"Area di Lavoro \" ><\/div><div id=\"wpforms-6832-field_21-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-hide\" data-field-type=\"text\" data-field-id=\"21\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_21\">Nome della societ\u00e0<\/label><input type=\"text\" id=\"wpforms-6832-field_21\" class=\"wpforms-field-large\" name=\"wpforms[fields][21]\" placeholder=\"Nome della societ\u00e0\" ><\/div><div id=\"wpforms-6832-field_20-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-6832-field_20\">Ho partecipato a un programma IIS in passato <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-6832-field_20\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][20]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Seleziona<\/option><option value=\"S\u00ec\"  class=\"choice-1 depth-1\"  >S\u00ec<\/option><option value=\"No\"  class=\"choice-2 depth-1\"  >No<\/option><\/select><\/div><div id=\"wpforms-6832-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6832-field_2\">Scrivi il tuo messaggio<\/label><textarea id=\"wpforms-6832-field_2\" class=\"wpforms-field-large wpforms-limit-characters-enabled\" data-form-id=\"6832\" data-field-id=\"2\" data-text-limit=\"300\" name=\"wpforms[fields][2]\" placeholder=\"Scrivi il tuo messaggio\" maxlength=\"300\" ><\/textarea><\/div><div id=\"wpforms-6832-field_7-container\" class=\"wpforms-field wpforms-field-mailchimp\" data-field-type=\"mailchimp\" data-field-id=\"7\"><ul id=\"\" class=\"\"><li class=\"choice-0 depth-1\"><input type=\"checkbox\" id=\"wpforms-6832-field_7_0\" name=\"wpforms[fields][7]\" value=\"1\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6832-field_7_0\">Desidero ricevere e-mail\/messaggi\/telefonate da KEK10 per essere informato sui programmi di formazione e altri servizi.<\/label><\/li><\/ul><\/div><div id=\"wpforms-6832-field_6-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"6\"><label class=\"wpforms-field-label wpforms-label-hide\">Dati personali <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-6832-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1 wpforms-selected\"><input type=\"checkbox\" id=\"wpforms-6832-field_6_1\" name=\"wpforms[fields][6][]\" value=\"Inviando il modulo di cui sopra, accetto di fornire il mio consenso al trattamento dei miei dati personali come specificamente definito nel Regolamento generale sulla protezione dei dati GDPR.\" required  checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-6832-field_6_1\">Inviando il modulo di cui sopra, accetto di fornire il mio consenso al trattamento dei miei dati personali come specificamente definito nel Regolamento generale sulla protezione dei dati GDPR.<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-6832-field-hp\" class=\"wpforms-field-label\">Phone<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-6832-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"6832\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/posts\/6811\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-6832\" class=\"wpforms-submit\" data-alt-text=\"Attendere prego...\" data-submit-text=\"Invia un messaggio\" aria-live=\"assertive\" value=\"wpforms-submit\">Invia un messaggio<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd30221 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd30221\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f4abfe7\" data-id=\"f4abfe7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccb17db elementor-widget elementor-widget-image\" data-id=\"ccb17db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"70\" src=\"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/10\/image-2-300x70.png\" class=\"attachment-medium size-medium wp-image-1577\" alt=\"\" srcset=\"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/10\/image-2-300x70.png 300w, https:\/\/kek10.gr\/wp-content\/uploads\/2023\/10\/image-2-768x180.png 768w, https:\/\/kek10.gr\/wp-content\/uploads\/2023\/10\/image-2.png 792w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-383e253\" data-id=\"383e253\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85f9bcd elementor-widget elementor-widget-image\" data-id=\"85f9bcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"52\" height=\"40\" src=\"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/09\/dypa.jpg\" class=\"attachment-medium size-medium wp-image-657\" alt=\"\u0394\u03b7\u03bc\u03cc\u03c3\u03b9\u03b1 \u03a5\u03c0\u03b7\u03c1\u03b5\u03c3\u03af\u03b1 \u0391\u03c0\u03b1\u03c3\u03c7\u03cc\u03bb\u03b7\u03c3\u03b7\u03c2\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ORA FORMAZIONE 100% A DISTANZA &#8211; NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO! Lo scopo del programma \u00e8 l&#8217;aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato. Nello [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7498,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[38,37],"tags":[],"class_list":["post-6811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voucher-per-dipendenti-del-settore-privato","category-voucher-per-i-dipendenti"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"ORA FORMAZIONE 100% A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!Lo scopo del programma \u00e8 l\u2019aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.Nello specifico, il programma mira all\u2019acquisizione e\/o all\u2019aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\u00e9 all\u2019ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"KEK10 KEK10\"\/>\n\t<meta name=\"msvalidate.01\" content=\"1BA7350B3201CB29DAA0A727B06DDCA1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"KEK10 -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO! - KEK10, \u03a0\u03c1\u03bf\u03b3\u03c1\u03ac\u03bc\u03bc\u03b1\u03c4\u03b1 \u03b3\u03b9\u03b1 \u0391\u03bd\u03ad\u03c1\u03b3\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5\u03c2, \u03a3\u03b5\u03bc\u03b9\u03bd\u03ac\u03c1\u03b9\u03b1\" \/>\n\t\t<meta property=\"og:description\" content=\"ORA FORMAZIONE 100% A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!Lo scopo del programma \u00e8 l\u2019aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.Nello specifico, il programma mira all\u2019acquisizione e\/o all\u2019aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\u00e9 all\u2019ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/09\/kek10-logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/09\/kek10-logo.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t\t<meta property=\"og:image:height\" content=\"113\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-17T12:15:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-06T11:44:02+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kek10kdvm\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO! - KEK10, \u03a0\u03c1\u03bf\u03b3\u03c1\u03ac\u03bc\u03bc\u03b1\u03c4\u03b1 \u03b3\u03b9\u03b1 \u0391\u03bd\u03ad\u03c1\u03b3\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5\u03c2, \u03a3\u03b5\u03bc\u03b9\u03bd\u03ac\u03c1\u03b9\u03b1\" \/>\n\t\t<meta name=\"twitter:description\" content=\"ORA FORMAZIONE 100% A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!Lo scopo del programma \u00e8 l\u2019aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.Nello specifico, il programma mira all\u2019acquisizione e\/o all\u2019aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\u00e9 all\u2019ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/09\/kek10-logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#blogposting\",\"name\":\"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\\u20ac ORA 100% FORMAZIONE A DISTANZA \\u2013 NEL TEMPO CHE TI \\u00c8 PI\\u00d9 COMODO! - KEK10, \\u03a0\\u03c1\\u03bf\\u03b3\\u03c1\\u03ac\\u03bc\\u03bc\\u03b1\\u03c4\\u03b1 \\u03b3\\u03b9\\u03b1 \\u0391\\u03bd\\u03ad\\u03c1\\u03b3\\u03bf\\u03c5\\u03c2 \\u03ba\\u03b1\\u03b9 \\u0395\\u03c1\\u03b3\\u03b1\\u03b6\\u03cc\\u03bc\\u03b5\\u03bd\\u03bf\\u03c5\\u03c2, \\u03a3\\u03b5\\u03bc\\u03b9\\u03bd\\u03ac\\u03c1\\u03b9\\u03b1\",\"headline\":\"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\\u20ac ORA 100% FORMAZIONE A DISTANZA &#8211; NEL TEMPO CHE TI \\u00c8 PI\\u00d9 COMODO!\",\"author\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/author\\\/kek10\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/kek10.gr\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Artboard-8@2x.png\",\"width\":2161,\"height\":2161},\"datePublished\":\"2025-11-17T15:15:00+03:00\",\"dateModified\":\"2026-02-06T14:44:02+03:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#webpage\"},\"articleSection\":\"Voucher per dipendenti del settore privato, Voucher per i dipendenti, \\u03a0\\u03c1\\u03bf\\u03b1\\u03b9\\u03c1\\u03b5\\u03c4\\u03b9\\u03ba\\u03ac\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kek10.gr\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/category\\\/voucher-per-i-dipendenti\\\/#listItem\",\"name\":\"Voucher per i dipendenti\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/category\\\/voucher-per-i-dipendenti\\\/#listItem\",\"position\":2,\"name\":\"Voucher per i dipendenti\",\"item\":\"https:\\\/\\\/kek10.gr\\\/it\\\/category\\\/voucher-per-i-dipendenti\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/category\\\/voucher-per-i-dipendenti\\\/voucher-per-dipendenti-del-settore-privato\\\/#listItem\",\"name\":\"Voucher per dipendenti del settore privato\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/category\\\/voucher-per-i-dipendenti\\\/voucher-per-dipendenti-del-settore-privato\\\/#listItem\",\"position\":3,\"name\":\"Voucher per dipendenti del settore privato\",\"item\":\"https:\\\/\\\/kek10.gr\\\/it\\\/category\\\/voucher-per-i-dipendenti\\\/voucher-per-dipendenti-del-settore-privato\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#listItem\",\"name\":\"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\\u20ac ORA 100% FORMAZIONE A DISTANZA &#8211; NEL TEMPO CHE TI \\u00c8 PI\\u00d9 COMODO!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/category\\\/voucher-per-i-dipendenti\\\/#listItem\",\"name\":\"Voucher per i dipendenti\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#listItem\",\"position\":4,\"name\":\"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\\u20ac ORA 100% FORMAZIONE A DISTANZA &#8211; NEL TEMPO CHE TI \\u00c8 PI\\u00d9 COMODO!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/category\\\/voucher-per-i-dipendenti\\\/voucher-per-dipendenti-del-settore-privato\\\/#listItem\",\"name\":\"Voucher per dipendenti del settore privato\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/#organization\",\"name\":\"KEK10\",\"url\":\"https:\\\/\\\/kek10.gr\\\/it\\\/\",\"telephone\":\"+302106664106\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/kek10.gr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/kek10-logo.png\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#organizationLogo\",\"width\":225,\"height\":113,\"caption\":\"\\u039a\\u0395\\u039a10 \\u03a0\\u03b1\\u03bb\\u03bb\\u03ae\\u03bd\\u03b7\"},\"image\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kek10kdvm\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/author\\\/kek10\\\/#author\",\"url\":\"https:\\\/\\\/kek10.gr\\\/it\\\/author\\\/kek10\\\/\",\"name\":\"KEK10 KEK10\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#authorImage\",\"url\":\"https:\\\/\\\/kek10.gr\\\/wp-content\\\/litespeed\\\/avatar\\\/fa02689a87374e6bbeaadf0f9d52a143.jpg?ver=1787774676\",\"width\":96,\"height\":96,\"caption\":\"KEK10 KEK10\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#webpage\",\"url\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/\",\"name\":\"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\\u20ac ORA 100% FORMAZIONE A DISTANZA \\u2013 NEL TEMPO CHE TI \\u00c8 PI\\u00d9 COMODO! - KEK10, \\u03a0\\u03c1\\u03bf\\u03b3\\u03c1\\u03ac\\u03bc\\u03bc\\u03b1\\u03c4\\u03b1 \\u03b3\\u03b9\\u03b1 \\u0391\\u03bd\\u03ad\\u03c1\\u03b3\\u03bf\\u03c5\\u03c2 \\u03ba\\u03b1\\u03b9 \\u0395\\u03c1\\u03b3\\u03b1\\u03b6\\u03cc\\u03bc\\u03b5\\u03bd\\u03bf\\u03c5\\u03c2, \\u03a3\\u03b5\\u03bc\\u03b9\\u03bd\\u03ac\\u03c1\\u03b9\\u03b1\",\"description\":\"ORA FORMAZIONE 100% A DISTANZA \\u2013 NEL TEMPO CHE TI \\u00c8 PI\\u00d9 COMODO!Lo scopo del programma \\u00e8 l\\u2019aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.Nello specifico, il programma mira all\\u2019acquisizione e\\\/o all\\u2019aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\\u00e9 all\\u2019ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/author\\\/kek10\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/author\\\/kek10\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/kek10.gr\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Artboard-8@2x.png\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#mainImage\",\"width\":2161,\"height\":2161},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\\\/#mainImage\"},\"datePublished\":\"2025-11-17T15:15:00+03:00\",\"dateModified\":\"2026-02-06T14:44:02+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/kek10.gr\\\/it\\\/\",\"name\":\"KEK10, \\u03a0\\u03c1\\u03bf\\u03b3\\u03c1\\u03ac\\u03bc\\u03bc\\u03b1\\u03c4\\u03b1 \\u03b3\\u03b9\\u03b1 \\u0391\\u03bd\\u03ad\\u03c1\\u03b3\\u03bf\\u03c5\\u03c2 \\u03ba\\u03b1\\u03b9 \\u0395\\u03c1\\u03b3\\u03b1\\u03b6\\u03cc\\u03bc\\u03b5\\u03bd\\u03bf\\u03c5\\u03c2, \\u03a3\\u03b5\\u03bc\\u03b9\\u03bd\\u03ac\\u03c1\\u03b9\\u03b1\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/kek10.gr\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO! - KEK10, \u03a0\u03c1\u03bf\u03b3\u03c1\u03ac\u03bc\u03bc\u03b1\u03c4\u03b1 \u03b3\u03b9\u03b1 \u0391\u03bd\u03ad\u03c1\u03b3\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5\u03c2, \u03a3\u03b5\u03bc\u03b9\u03bd\u03ac\u03c1\u03b9\u03b1","description":"ORA FORMAZIONE 100% A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!Lo scopo del programma \u00e8 l\u2019aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.Nello specifico, il programma mira all\u2019acquisizione e\/o all\u2019aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\u00e9 all\u2019ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze","canonical_url":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"msvalidate.01":"1BA7350B3201CB29DAA0A727B06DDCA1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#blogposting","name":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO! - KEK10, \u03a0\u03c1\u03bf\u03b3\u03c1\u03ac\u03bc\u03bc\u03b1\u03c4\u03b1 \u03b3\u03b9\u03b1 \u0391\u03bd\u03ad\u03c1\u03b3\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5\u03c2, \u03a3\u03b5\u03bc\u03b9\u03bd\u03ac\u03c1\u03b9\u03b1","headline":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA &#8211; NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!","author":{"@id":"https:\/\/kek10.gr\/it\/author\/kek10\/#author"},"publisher":{"@id":"https:\/\/kek10.gr\/it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/kek10.gr\/wp-content\/uploads\/2025\/11\/Artboard-8@2x.png","width":2161,"height":2161},"datePublished":"2025-11-17T15:15:00+03:00","dateModified":"2026-02-06T14:44:02+03:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#webpage"},"isPartOf":{"@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#webpage"},"articleSection":"Voucher per dipendenti del settore privato, Voucher per i dipendenti, \u03a0\u03c1\u03bf\u03b1\u03b9\u03c1\u03b5\u03c4\u03b9\u03ba\u03ac"},{"@type":"BreadcrumbList","@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/kek10.gr\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/#listItem","name":"Voucher per i dipendenti"}},{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/#listItem","position":2,"name":"Voucher per i dipendenti","item":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/","nextItem":{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/voucher-per-dipendenti-del-settore-privato\/#listItem","name":"Voucher per dipendenti del settore privato"},"previousItem":{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/voucher-per-dipendenti-del-settore-privato\/#listItem","position":3,"name":"Voucher per dipendenti del settore privato","item":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/voucher-per-dipendenti-del-settore-privato\/","nextItem":{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#listItem","name":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA &#8211; NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/#listItem","name":"Voucher per i dipendenti"}},{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#listItem","position":4,"name":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA &#8211; NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!","previousItem":{"@type":"ListItem","@id":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/voucher-per-dipendenti-del-settore-privato\/#listItem","name":"Voucher per dipendenti del settore privato"}}]},{"@type":"Organization","@id":"https:\/\/kek10.gr\/it\/#organization","name":"KEK10","url":"https:\/\/kek10.gr\/it\/","telephone":"+302106664106","logo":{"@type":"ImageObject","url":"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/09\/kek10-logo.png","@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#organizationLogo","width":225,"height":113,"caption":"\u039a\u0395\u039a10 \u03a0\u03b1\u03bb\u03bb\u03ae\u03bd\u03b7"},"image":{"@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/kek10kdvm"]},{"@type":"Person","@id":"https:\/\/kek10.gr\/it\/author\/kek10\/#author","url":"https:\/\/kek10.gr\/it\/author\/kek10\/","name":"KEK10 KEK10","image":{"@type":"ImageObject","@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#authorImage","url":"https:\/\/kek10.gr\/wp-content\/litespeed\/avatar\/fa02689a87374e6bbeaadf0f9d52a143.jpg?ver=1787774676","width":96,"height":96,"caption":"KEK10 KEK10"}},{"@type":"WebPage","@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#webpage","url":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/","name":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO! - KEK10, \u03a0\u03c1\u03bf\u03b3\u03c1\u03ac\u03bc\u03bc\u03b1\u03c4\u03b1 \u03b3\u03b9\u03b1 \u0391\u03bd\u03ad\u03c1\u03b3\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5\u03c2, \u03a3\u03b5\u03bc\u03b9\u03bd\u03ac\u03c1\u03b9\u03b1","description":"ORA FORMAZIONE 100% A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!Lo scopo del programma \u00e8 l\u2019aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.Nello specifico, il programma mira all\u2019acquisizione e\/o all\u2019aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\u00e9 all\u2019ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/kek10.gr\/it\/#website"},"breadcrumb":{"@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#breadcrumblist"},"author":{"@id":"https:\/\/kek10.gr\/it\/author\/kek10\/#author"},"creator":{"@id":"https:\/\/kek10.gr\/it\/author\/kek10\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/kek10.gr\/wp-content\/uploads\/2025\/11\/Artboard-8@2x.png","@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#mainImage","width":2161,"height":2161},"primaryImageOfPage":{"@id":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/#mainImage"},"datePublished":"2025-11-17T15:15:00+03:00","dateModified":"2026-02-06T14:44:02+03:00"},{"@type":"WebSite","@id":"https:\/\/kek10.gr\/it\/#website","url":"https:\/\/kek10.gr\/it\/","name":"KEK10, \u03a0\u03c1\u03bf\u03b3\u03c1\u03ac\u03bc\u03bc\u03b1\u03c4\u03b1 \u03b3\u03b9\u03b1 \u0391\u03bd\u03ad\u03c1\u03b3\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5\u03c2, \u03a3\u03b5\u03bc\u03b9\u03bd\u03ac\u03c1\u03b9\u03b1","inLanguage":"it-IT","publisher":{"@id":"https:\/\/kek10.gr\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"KEK10 -","og:type":"article","og:title":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO! - KEK10, \u03a0\u03c1\u03bf\u03b3\u03c1\u03ac\u03bc\u03bc\u03b1\u03c4\u03b1 \u03b3\u03b9\u03b1 \u0391\u03bd\u03ad\u03c1\u03b3\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5\u03c2, \u03a3\u03b5\u03bc\u03b9\u03bd\u03ac\u03c1\u03b9\u03b1","og:description":"ORA FORMAZIONE 100% A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!Lo scopo del programma \u00e8 l\u2019aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.Nello specifico, il programma mira all\u2019acquisizione e\/o all\u2019aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\u00e9 all\u2019ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze","og:url":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/","og:image":"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/09\/kek10-logo.png","og:image:secure_url":"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/09\/kek10-logo.png","og:image:width":225,"og:image:height":113,"article:published_time":"2025-11-17T12:15:00+00:00","article:modified_time":"2026-02-06T11:44:02+00:00","article:publisher":"https:\/\/www.facebook.com\/kek10kdvm","twitter:card":"summary_large_image","twitter:title":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO! - KEK10, \u03a0\u03c1\u03bf\u03b3\u03c1\u03ac\u03bc\u03bc\u03b1\u03c4\u03b1 \u03b3\u03b9\u03b1 \u0391\u03bd\u03ad\u03c1\u03b3\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5\u03c2, \u03a3\u03b5\u03bc\u03b9\u03bd\u03ac\u03c1\u03b9\u03b1","twitter:description":"ORA FORMAZIONE 100% A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!Lo scopo del programma \u00e8 l\u2019aggiornamento delle conoscenze e delle competenze dei lavoratori del settore privato.Nello specifico, il programma mira all\u2019acquisizione e\/o all\u2019aggiornamento delle conoscenze e competenze professionali dei beneficiari, nonch\u00e9 all\u2019ottenimento di una certificazione correlata, al fine di rispondere alle moderne esigenze","twitter:image":"https:\/\/kek10.gr\/wp-content\/uploads\/2023\/09\/kek10-logo.png"},"aioseo_meta_data":{"post_id":"6811","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-06 14:22:57","updated":"2026-02-06 11:44:38","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kek10.gr\/it\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/\" title=\"Voucher per i dipendenti\">Voucher per i dipendenti<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/voucher-per-dipendenti-del-settore-privato\/\" title=\"Voucher per dipendenti del settore privato\">Voucher per dipendenti del settore privato<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA \u2013 NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/kek10.gr\/it\/"},{"label":"Voucher per i dipendenti","link":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/"},{"label":"Voucher per dipendenti del settore privato","link":"https:\/\/kek10.gr\/it\/category\/voucher-per-i-dipendenti\/voucher-per-dipendenti-del-settore-privato\/"},{"label":"VOUCHER PER DIPENDENTI CON COMPENSO DI 750\u20ac ORA 100% FORMAZIONE A DISTANZA &#8211; NEL TEMPO CHE TI \u00c8 PI\u00d9 COMODO!","link":"https:\/\/kek10.gr\/it\/nuovo-voucher-per-lavoratori-e-disoccupati-con-compenso-fino-a-750e-copia\/"}],"_links":{"self":[{"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/posts\/6811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/comments?post=6811"}],"version-history":[{"count":41,"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/posts\/6811\/revisions"}],"predecessor-version":[{"id":7518,"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/posts\/6811\/revisions\/7518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/media\/7498"}],"wp:attachment":[{"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/media?parent=6811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/categories?post=6811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kek10.gr\/it\/wp-json\/wp\/v2\/tags?post=6811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}